{"id":13,"date":"2018-04-16T08:50:09","date_gmt":"2018-04-16T11:50:09","guid":{"rendered":"http:\/\/localhost\/base\/sitenovo\/?page_id=13"},"modified":"2023-10-24T11:24:15","modified_gmt":"2023-10-24T14:24:15","slug":"quem-somos","status":"publish","type":"page","link":"https:\/\/www.este.com.py\/pt\/quem-somos\/","title":{"rendered":"Quem Somos"},"content":{"rendered":"\r\n<p>A <strong>ESTE ADMINISTRA\u00c7\u00c3O E CONSULTORIA FINANCEIRA<\/strong> atua no gerenciamento e otimiza\u00e7\u00e3o de ativos pr\u00f3prios e de seus clientes e parceiros, trabalhando de forma multisetorial e atenta aos cen\u00e1rios de v\u00e1rios pa\u00edses. Com uma equipe de profissionais experientes e especializados, a empresa oferece ampla gama de atividades e servi\u00e7os voltados para maximizar o valor dos ativos sob sua responsabilidade.<\/p>\r\n\r\n\r\n\r\n<p>Uma das principais atividades da <strong>ESTE Administradora de Ativos<\/strong> \u00e9 a an\u00e1lise e avalia\u00e7\u00e3o de diferentes classes de ativos como a\u00e7\u00f5es, t\u00edtulos, im\u00f3veis e investimentos alternativos. As estrat\u00e9gias de investimento s\u00e3o desenvolvidas com base nessa an\u00e1lise, respeitando os objetivos e a toler\u00e2ncia ao risco de cada cliente.<\/p>\r\n\r\n\r\n\r\n<p>Al\u00e9m disso, sempre focamos na diversifica\u00e7\u00e3o da carteira de ativos, por meio da aloca\u00e7\u00e3o adequada dos recursos financeiros com objetivo de buscar a maximiza\u00e7\u00e3o dos retornos conjuntamente com o controle e diminui\u00e7\u00e3o dos riscos.<\/p>\r\n\r\n\r\n\r\n<p>A diversifica\u00e7\u00e3o envolve, al\u00e9m da classe dos ativos, a distribui\u00e7\u00e3o dos investimentos em diferentes setores e regi\u00f5es geogr\u00e1ficas do mundo.<\/p>\r\n\r\n\r\n\r\n<p>Al\u00e9m da an\u00e1lise e aloca\u00e7\u00e3o dos recursos, outra atividade importante da <strong>ESTE Administradora de Ativos<\/strong> \u00e9 o monitoramento cont\u00ednuo do valor e desempenho dos ativos e projetos, se valendo do acompanhamento dos mercados financeiros e dos cen\u00e1rios econ\u00f4micos de diversas regi\u00f5es do mundo, identificando oportunidades de compra e venda. Esse monitoramento \u00e9 a ferramenta que permite os ajustes estrat\u00e9gicos para garantir o alinhamento \u00e0s metas do cliente.<\/p>\r\n\r\n\r\n\r\n<p>Tamb\u00e9m fornecemos relat\u00f3rios e presta\u00e7\u00f5es de contas detalhados e transparentes sobre o desempenho dos ativos administrados, permitindo que os clientes acompanhem de perto o progresso de seus projetos e investimentos. Os relat\u00f3rios informam, al\u00e9m do conte\u00fado regulat\u00f3rio, o valor de mercado dos ativos, rendimentos, despesas, fluxo de caixa e indicadores relevantes de desempenho comparado.<\/p>\r\n\r\n\r\n\r\n<p>Em resumo, a <strong>ESTE Administradora de Ativos<\/strong> oferece diversos servi\u00e7os para maximizar seus objetivos e investimentos, com seguran\u00e7a e lucratividade.<\/p>\r\n\r\n\r\n\r\n<p>A <strong>ESTE Administradora de Ativos<\/strong> est\u00e1 h\u00e1 10 anos no mercado e opera desde de 2014, com sede no Paran\u00e1 Country Club na cidade de Hernandarias, departamento do Alto Paran\u00e1, Paraguai. Nossa origem foi motivada pelo crescimento econ\u00f4mico e desenvolvimento financeiro e social do Paraguai, mais especificamente a regi\u00e3o da fronteira leste, por suas peculiaridades. O estabelecimento e configura\u00e7\u00e3o da empresa foram definidos com o objetivo de administrar os ativos e patrim\u00f4nio pr\u00f3prios e de seus clientes.<\/p>\r\n\r\n\r\n\r\n<p>Somos a empresa pioneira no setor de administra\u00e7\u00e3o de ativos financeiros da regi\u00e3o e permanecemos no mercado at\u00e9 os dias atuais, com boa rentabilidade e confiabilidade operacional hist\u00f3rica.<\/p>\r\n\r\n\r\n\r\n<p>Desde o in\u00edcio de nossas opera\u00e7\u00f5es, buscamos fundamentos e ferramentas modernas e vanguardistas para gerar o maior ganho poss\u00edvel, com risco adequadamente controlado e utilizando o mercado de capitais mundial para conquistar essa meta.<\/p>\r\n\r\n\r\n\r\n<p>A <strong>ESTE Administradora de Ativos<\/strong> \u00e9 a \u00fanica empresa da regi\u00e3o da tr\u00edplice fronteira sulamericana (Paraguai, Brasil e Argentina) que atua resilientemente neste setor e nossa larga experi\u00eancia no Paraguai, bem como o excelente desempenho operacional, s\u00e3o ferramentas competitivas para os nossos clientes.<\/p>\r\n\r\n\r\n\r\n<p>Al\u00e9m da administra\u00e7\u00e3o de ativos, oferecemos servi\u00e7os de Consultoria Financeira e de Mercado de Capitais (no Paraguai e no exterior \u2013 Am\u00e9rica do Sul, Am\u00e9rica do Norte, Europa, entre outros) a pessoas f\u00edsicas e empresas que queiram realizar opera\u00e7\u00f5es de investimentos rent\u00e1veis e com risco adequado. Nessa atividade, realizamos an\u00e1lises econ\u00f4micas e financeiras, estrat\u00e9gicas e operacionais com objetivo de fornecer informa\u00e7\u00e3o para tomada de decis\u00e3o de nossos clientes para que atinjam seus objetivos de projeto e investimentos.<\/p>\r\n\r\n\r\n\r\n<p>Como parte da consultoria financeira e de nossa experi\u00eancia operacional pr\u00f3pria, tamb\u00e9m temos a expertise em Consultoria Empresarial para empresas de diversos portes e\/ou empreendedores que buscam se estabelecer no Paraguai. Auxiliamos nossos clientes com orienta\u00e7\u00e3o e informa\u00e7\u00e3o para que se possam realizar todos os tr\u00e2mites legais e informa\u00e7\u00f5es estrat\u00e9gicas adequadas para o bom in\u00edcio e continua\u00e7\u00e3o de seus projetos, empreendimentos e investimentos, melhorando o desempenho, a viabilidade, a rentabilidade e controlando os custos.<\/p>\r\n\r\n\r\n\r\n<p>A ESTE oferece todos os seus servi\u00e7os de maneira eficiente, transparente, legal e em formato totalmente digital.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>A ESTE ADMINISTRA\u00c7\u00c3O E CONSULTORIA FINANCEIRA atua no gerenciamento e otimiza\u00e7\u00e3o de ativos pr\u00f3prios e de seus clientes e parceiros, trabalhando de forma multisetorial e atenta aos cen\u00e1rios de v\u00e1rios pa\u00edses. Com uma equipe de profissionais experientes e especializados, a empresa oferece ampla gama de atividades e servi\u00e7os voltados para maximizar o valor dos ativos &hellip; <a href=\"https:\/\/www.este.com.py\/pt\/quem-somos\/\">Continua<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-default.php","meta":{"_es_post_content":"<!-- wp:paragraph -->\r\n<p><strong>ESTE ADMINISTRACI\u00d3N Y CONSULTOR\u00cdA FINANCIERA<\/strong> act\u00faa en la gesti\u00f3n y optimizaci\u00f3n de sus activos y de sus clientes y socios, trabajando de forma multisectorial y atenta a los escenarios de los diversos pa\u00edses. Con un equipo de profesionales experimentados y especializados, la empresa ofrece una amplia gama de actividades y servicios encaminados a maximizar el valor de los activos bajo su responsabilidad.<\/p>\r\n<p>Una de las principales actividades de ESTE es el an\u00e1lisis y evaluaci\u00f3n de diferentes clases de activos como acciones, bonos, bienes ra\u00edces e inversiones alternativas. Las estrategias de inversi\u00f3n se desarrollan en base a este an\u00e1lisis, respetando los objetivos y la tolerancia al riesgo de cada cliente.<\/p>\r\n<p>Adem\u00e1s, siempre nos centramos en diversificar la cartera de activos, mediante la adecuada asignaci\u00f3n de recursos financieros con el objetivo de buscar maximizar la rentabilidad junto con controlar y reducir los riesgos. La diversificaci\u00f3n implica, adem\u00e1s de la clase de activos, la distribuci\u00f3n de las inversiones en diferentes sectores y regiones geogr\u00e1ficas del mundo.<\/p>\r\n<p>Adem\u00e1s del an\u00e1lisis y asignaci\u00f3n de recursos, otra actividad importante de <strong>ESTE<\/strong> es el seguimiento continuo del valor y desempe\u00f1o de activos y proyectos, utilizando el seguimiento de los mercados financieros y escenarios econ\u00f3micos en diferentes regiones del mundo, identificando compras oportunidades y venta. Este seguimiento es la herramienta que permite realizar ajustes estrat\u00e9gicos para asegurar el alineamiento con los objetivos del cliente.<\/p>\r\n<p>Tambi\u00e9n proporcionamos informes y rendici\u00f3n de cuentas detallados y transparentes sobre el desempe\u00f1o de los activos administrados, lo que permite a los clientes monitorear de cerca el progreso de sus proyectos e inversiones. Los informes brindan, adem\u00e1s del contenido regulatorio, el valor de mercado de los activos, ingresos, gastos, flujo de caja e indicadores relevantes de desempe\u00f1o comparativo.<\/p>\r\n<p>En resumen, <strong>ESTE<\/strong> ofrece varios servicios para maximizar sus objetivos e inversiones, con seguridad y rentabilidad.<\/p>\r\n<p><strong>ESTE Administraci\u00f3n y Consultor\u00eda Financiera<\/strong> tiene 10 a\u00f1os en el mercado y opera desde el a\u00f1o 2014, con sede en el Paran\u00e1 Country Club en la ciudad de Hernandarias, departamento de Alto Paran\u00e1, Paraguay. Nuestro origen estuvo motivado por el crecimiento econ\u00f3mico y el desarrollo financiero y social del Paraguay, m\u00e1s espec\u00edficamente de la regi\u00f3n fronteriza oriental, por sus peculiaridades. La constituci\u00f3n y configuraci\u00f3n de la empresa se defini\u00f3 con el objetivo de<br \/>administrar bienes y activos propios y de sus clientes. Somos la empresa pionera en el sector de administraci\u00f3n de activos financieros en la regi\u00f3n y nos mantuvimos en el mercado hasta el d\u00eda de hoy, con buena rentabilidad y confiabilidad operativa hist\u00f3rica.<\/p>\r\n<p>Desde el inicio de nuestras operaciones, hemos buscado fundamentos y herramientas modernas y de vanguardia para generar la mayor ganancia posible, con el riesgo adecuadamente controlado y utilizando el mercado de capitales global para lograr este objetivo.<\/p>\r\n<p><strong>ESTE Administraci\u00f3n y Consultor\u00eda Financiera<\/strong> es la \u00fanica empresa en la regi\u00f3n de la triple frontera de Am\u00e9rica del Sur (Paraguay, Brasil y Argentina) que opera de manera resiliente en este sector y nuestra amplia experiencia en Paraguay, as\u00ed como un excelente desempe\u00f1o operativo, son herramientas competitivas para nuestros clientes.<\/p>\r\n<p>Adem\u00e1s de la gesti\u00f3n de activos, ofrecemos servicios de Consultor\u00eda Financiera y Mercado de Capitales (en Paraguay y en el extranjero \u2013 Sudam\u00e9rica, Norteam\u00e9rica, Europa, entre otros) a personas f\u00edsicas y jur\u00eddicas que quieran realizar operaciones de inversi\u00f3n rentables y con el riesgo adecuado. En esta actividad realizamos an\u00e1lisis econ\u00f3micos y financieros, estrat\u00e9gicos y operativos con el objetivo de brindar informaci\u00f3n a nuestros clientes para la toma de decisiones que les permitan alcanzar sus objetivos de proyecto e inversi\u00f3n.<\/p>\r\n<p>Como parte de la consultor\u00eda financiera y de nuestra propia experiencia operativa, tambi\u00e9n contamos con experiencia en Consultor\u00eda de Negocios para empresas de diferentes tama\u00f1os y\/o emprendedores que buscan establecerse en Paraguay. Ayudamos a nuestros clientes con orientaci\u00f3n e informaci\u00f3n para que puedan realizar todos los tr\u00e1mites legales e informaci\u00f3n estrat\u00e9gica adecuada para el exitoso inicio y continuaci\u00f3n de sus proyectos, emprendimientos e inversiones, <br \/>mejorando el desempe\u00f1o, viabilidad, rentabilidad y controlando costos.<\/p>\r\n<p><strong>ESTE<\/strong> ofrece todos sus servicios de forma eficiente, transparente, legal y en un formato completamente digital.<\/p>\r\n<!-- \/wp:paragraph -->","_es_post_name":"quienes-somos","_es_post_excerpt":"","_es_post_title":"Quienes somos","_pt_post_content":"<!-- wp:paragraph -->\r\n<p>A <strong>ESTE ADMINISTRA\u00c7\u00c3O E CONSULTORIA FINANCEIRA<\/strong> atua no gerenciamento e otimiza\u00e7\u00e3o de ativos pr\u00f3prios e de seus clientes e parceiros, trabalhando de forma multisetorial e atenta aos cen\u00e1rios de v\u00e1rios pa\u00edses. Com uma equipe de profissionais experientes e especializados, a empresa oferece ampla gama de atividades e servi\u00e7os voltados para maximizar o valor dos ativos sob sua responsabilidade.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Uma das principais atividades da <strong>ESTE Administradora de Ativos<\/strong> \u00e9 a an\u00e1lise e avalia\u00e7\u00e3o de diferentes classes de ativos como a\u00e7\u00f5es, t\u00edtulos, im\u00f3veis e investimentos alternativos. As estrat\u00e9gias de investimento s\u00e3o desenvolvidas com base nessa an\u00e1lise, respeitando os objetivos e a toler\u00e2ncia ao risco de cada cliente.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Al\u00e9m disso, sempre focamos na diversifica\u00e7\u00e3o da carteira de ativos, por meio da aloca\u00e7\u00e3o adequada dos recursos financeiros com objetivo de buscar a maximiza\u00e7\u00e3o dos retornos conjuntamente com o controle e diminui\u00e7\u00e3o dos riscos.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>A diversifica\u00e7\u00e3o envolve, al\u00e9m da classe dos ativos, a distribui\u00e7\u00e3o dos investimentos em diferentes setores e regi\u00f5es geogr\u00e1ficas do mundo.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Al\u00e9m da an\u00e1lise e aloca\u00e7\u00e3o dos recursos, outra atividade importante da <strong>ESTE Administradora de Ativos<\/strong> \u00e9 o monitoramento cont\u00ednuo do valor e desempenho dos ativos e projetos, se valendo do acompanhamento dos mercados financeiros e dos cen\u00e1rios econ\u00f4micos de diversas regi\u00f5es do mundo, identificando oportunidades de compra e venda. Esse monitoramento \u00e9 a ferramenta que permite os ajustes estrat\u00e9gicos para garantir o alinhamento \u00e0s metas do cliente.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Tamb\u00e9m fornecemos relat\u00f3rios e presta\u00e7\u00f5es de contas detalhados e transparentes sobre o desempenho dos ativos administrados, permitindo que os clientes acompanhem de perto o progresso de seus projetos e investimentos. Os relat\u00f3rios informam, al\u00e9m do conte\u00fado regulat\u00f3rio, o valor de mercado dos ativos, rendimentos, despesas, fluxo de caixa e indicadores relevantes de desempenho comparado.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Em resumo, a <strong>ESTE Administradora de Ativos<\/strong> oferece diversos servi\u00e7os para maximizar seus objetivos e investimentos, com seguran\u00e7a e lucratividade.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>A <strong>ESTE Administradora de Ativos<\/strong> est\u00e1 h\u00e1 10 anos no mercado e opera desde de 2014, com sede no Paran\u00e1 Country Club na cidade de Hernandarias, departamento do Alto Paran\u00e1, Paraguai. Nossa origem foi motivada pelo crescimento econ\u00f4mico e desenvolvimento financeiro e social do Paraguai, mais especificamente a regi\u00e3o da fronteira leste, por suas peculiaridades. O estabelecimento e configura\u00e7\u00e3o da empresa foram definidos com o objetivo de administrar os ativos e patrim\u00f4nio pr\u00f3prios e de seus clientes.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Somos a empresa pioneira no setor de administra\u00e7\u00e3o de ativos financeiros da regi\u00e3o e permanecemos no mercado at\u00e9 os dias atuais, com boa rentabilidade e confiabilidade operacional hist\u00f3rica.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Desde o in\u00edcio de nossas opera\u00e7\u00f5es, buscamos fundamentos e ferramentas modernas e vanguardistas para gerar o maior ganho poss\u00edvel, com risco adequadamente controlado e utilizando o mercado de capitais mundial para conquistar essa meta.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>A <strong>ESTE Administradora de Ativos<\/strong> \u00e9 a \u00fanica empresa da regi\u00e3o da tr\u00edplice fronteira sulamericana (Paraguai, Brasil e Argentina) que atua resilientemente neste setor e nossa larga experi\u00eancia no Paraguai, bem como o excelente desempenho operacional, s\u00e3o ferramentas competitivas para os nossos clientes.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Al\u00e9m da administra\u00e7\u00e3o de ativos, oferecemos servi\u00e7os de Consultoria Financeira e de Mercado de Capitais (no Paraguai e no exterior \u2013 Am\u00e9rica do Sul, Am\u00e9rica do Norte, Europa, entre outros) a pessoas f\u00edsicas e empresas que queiram realizar opera\u00e7\u00f5es de investimentos rent\u00e1veis e com risco adequado. Nessa atividade, realizamos an\u00e1lises econ\u00f4micas e financeiras, estrat\u00e9gicas e operacionais com objetivo de fornecer informa\u00e7\u00e3o para tomada de decis\u00e3o de nossos clientes para que atinjam seus objetivos de projeto e investimentos.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Como parte da consultoria financeira e de nossa experi\u00eancia operacional pr\u00f3pria, tamb\u00e9m temos a expertise em Consultoria Empresarial para empresas de diversos portes e\/ou empreendedores que buscam se estabelecer no Paraguai. Auxiliamos nossos clientes com orienta\u00e7\u00e3o e informa\u00e7\u00e3o para que se possam realizar todos os tr\u00e2mites legais e informa\u00e7\u00f5es estrat\u00e9gicas adequadas para o bom in\u00edcio e continua\u00e7\u00e3o de seus projetos, empreendimentos e investimentos, melhorando o desempenho, a viabilidade, a rentabilidade e controlando os custos.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>A ESTE oferece todos os seus servi\u00e7os de maneira eficiente, transparente, legal e em formato totalmente digital.<\/p>\r\n<!-- \/wp:paragraph -->","_pt_post_name":"quem-somos","_pt_post_excerpt":"","_pt_post_title":"Quem Somos","_en_post_content":"<p><strong>ESTE ASSET MANAGEMENT AND FINANCIAL CONSULTING<\/strong> operates in the management and optimization of its own assets and those of its clients and partners, working in a multi sectorial platform and attentive to the scenarios and conditions of multiple countries. With a team of with an experienced and specialized professionals team, the company offers a wide range of activities and services aimed to maximizing the value and profitability of the assets under its responsibility.<\/p>\r\n<p>One of the main activities of <strong>ESTE<\/strong> is the analysis and evaluation of different asset types such as shares, bonds, real estate and alternative investments. Investment strategies are developed based on these analyses, respecting the objectives and risk tolerance of each client. In addition, we always focus on diversifying the asset portfolio, through the appropriate allocation of financial resources with the aim of seeking to maximize returns together with risk\u2019s control and reducing.<\/p>\r\n<p>Diversification involves, in addition to the asset types, the distribution of investments across different sectors and geographic regions in the world.<\/p>\r\n<p>In addition to the analysis and allocation of resources, another important <strong>ESTE<\/strong>\u2019s activity is the continuous value and performance monitoring of assets and projects, using monitored data of financial markets and economic scenarios in different regions of the world, identifying purchase buy and sell opportunities. This monitoring procedure is the tool that allows strategic adjustments to ensure alignment with the client\u2019s goals.<\/p>\r\n<p>We also provide detailed and transparent reporting and accountability on the performance of managed assets, allowing clients to closely monitorate the progress of their projects and investments. The reports inform, in addition to the regulatory content, the market value of assets, income, expenses, cash flow and relevant indicators of comparative performance. In summary, <strong>ESTE<\/strong> offers several services to maximize your objectives and investments, with security and profitability.<\/p>\r\n<p><strong>ESTE Asset Management<\/strong> has been on the market for 10 years and has been operating since 2014, headquartered at the Paran\u00e1 Country Club in the city of Hernandarias, department of Alto Paran\u00e1, Paraguay. Our origin was motivated by the economic growth and financial and social development of Paraguay, more specifically the eastern border region, due to its peculiarities. The establishment and configuration of the company were defined with the objective of managing its own and its clients\u2019 assets.<\/p>\r\n<p>We are the pioneer company in the financial asset management and financial consulting sector in the region and have remained on the market until actuality, performing a good profitability and historical operational reliability.<\/p>\r\n<p>Since the beginning of our operations, we research and find modern and avant-garde fundamentals and tools to generate the bigger possible gain, with appropriately controlled risk and using the global capital market to achieve these objectives.<\/p>\r\n<p><strong>ESTE<\/strong> is the only company in the South American triple South American border (Paraguay, Brazil and Argentina) that operates resiliently in this sector and our extensive experience in Paraguay, as well as excellent operational performance, are competitive tools for us and our clients.<\/p>\r\n<p>In addition to asset management activity, we offer Financial and Capital Market Consulting (in Paraguay and abroad \u2013 South America, North America, Europe, etc.) to individuals and companies that want to carry out profitable investment operations with adequate risk. In this activity, we do economic and financial analyzes with the aim of providing information for our clients to make decisions so that they can achieve their project and investment objectives.<\/p>\r\n<p>As part of financial consultancy and our own operational experience, we also have expertise in Business Consulting for companies of different sizes and\/or entrepreneurs seeking to establish themselves in Paraguay. We help our clients with guidance and information so that they can execute all legal procedures and appropriate strategic information for the successful start and continuation of their projects, enterprise and investments, improving performance, viability, profitability and controlling costs.<\/p>\r\n<p><strong>ESTE<\/strong> offers all its services in an efficient, transparent, legal manner and in a completely digital platform.<\/p>","_en_post_name":"about-us","_en_post_excerpt":"","_en_post_title":"About us","edit_language":"pt","footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quem Somos - ESTE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.este.com.py\/en\/about-us\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quem Somos - ESTE\" \/>\n<meta property=\"og:description\" content=\"A ESTE ADMINISTRA\u00c7\u00c3O E CONSULTORIA FINANCEIRA atua no gerenciamento e otimiza\u00e7\u00e3o de ativos pr\u00f3prios e de seus clientes e parceiros, trabalhando de forma multisetorial e atenta aos cen\u00e1rios de v\u00e1rios pa\u00edses. Com uma equipe de profissionais experientes e especializados, a empresa oferece ampla gama de atividades e servi\u00e7os voltados para maximizar o valor dos ativos &hellip; Continua\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.este.com.py\/en\/about-us\/\" \/>\n<meta property=\"og:site_name\" content=\"ESTE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/esteadmpy\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-24T14:24:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.este.com.py\/wp-content\/uploads\/2023\/05\/seo-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.este.com.py\/en\/about-us\/\",\"url\":\"https:\/\/www.este.com.py\/en\/about-us\/\",\"name\":\"Quem Somos - ESTE\",\"isPartOf\":{\"@id\":\"https:\/\/www.este.com.py\/#website\"},\"datePublished\":\"2018-04-16T11:50:09+00:00\",\"dateModified\":\"2023-10-24T14:24:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.este.com.py\/en\/about-us\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.este.com.py\/en\/about-us\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.este.com.py\/en\/about-us\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.este.com.py\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quem Somos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.este.com.py\/#website\",\"url\":\"https:\/\/www.este.com.py\/\",\"name\":\"ESTE\",\"description\":\"Administraci\u00f3n Consultoria Financiera\",\"publisher\":{\"@id\":\"https:\/\/www.este.com.py\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.este.com.py\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.este.com.py\/#organization\",\"name\":\"ESTE\",\"url\":\"https:\/\/www.este.com.py\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.este.com.py\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.este.com.py\/andre\/wp-content\/uploads\/2023\/05\/seo-2.png\",\"contentUrl\":\"https:\/\/www.este.com.py\/andre\/wp-content\/uploads\/2023\/05\/seo-2.png\",\"width\":696,\"height\":696,\"caption\":\"ESTE\"},\"image\":{\"@id\":\"https:\/\/www.este.com.py\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/esteadmpy\",\"https:\/\/www.instagram.com\/esteadmpy\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quem Somos - ESTE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.este.com.py\/en\/about-us\/","og_locale":"pt_BR","og_type":"article","og_title":"Quem Somos - ESTE","og_description":"A ESTE ADMINISTRA\u00c7\u00c3O E CONSULTORIA FINANCEIRA atua no gerenciamento e otimiza\u00e7\u00e3o de ativos pr\u00f3prios e de seus clientes e parceiros, trabalhando de forma multisetorial e atenta aos cen\u00e1rios de v\u00e1rios pa\u00edses. Com uma equipe de profissionais experientes e especializados, a empresa oferece ampla gama de atividades e servi\u00e7os voltados para maximizar o valor dos ativos &hellip; Continua","og_url":"https:\/\/www.este.com.py\/en\/about-us\/","og_site_name":"ESTE","article_publisher":"https:\/\/www.facebook.com\/esteadmpy","article_modified_time":"2023-10-24T14:24:15+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.este.com.py\/wp-content\/uploads\/2023\/05\/seo-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.este.com.py\/en\/about-us\/","url":"https:\/\/www.este.com.py\/en\/about-us\/","name":"Quem Somos - ESTE","isPartOf":{"@id":"https:\/\/www.este.com.py\/#website"},"datePublished":"2018-04-16T11:50:09+00:00","dateModified":"2023-10-24T14:24:15+00:00","breadcrumb":{"@id":"https:\/\/www.este.com.py\/en\/about-us\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.este.com.py\/en\/about-us\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.este.com.py\/en\/about-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.este.com.py\/"},{"@type":"ListItem","position":2,"name":"Quem Somos"}]},{"@type":"WebSite","@id":"https:\/\/www.este.com.py\/#website","url":"https:\/\/www.este.com.py\/","name":"ESTE","description":"Administraci\u00f3n Consultoria Financiera","publisher":{"@id":"https:\/\/www.este.com.py\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.este.com.py\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.este.com.py\/#organization","name":"ESTE","url":"https:\/\/www.este.com.py\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.este.com.py\/#\/schema\/logo\/image\/","url":"https:\/\/www.este.com.py\/andre\/wp-content\/uploads\/2023\/05\/seo-2.png","contentUrl":"https:\/\/www.este.com.py\/andre\/wp-content\/uploads\/2023\/05\/seo-2.png","width":696,"height":696,"caption":"ESTE"},"image":{"@id":"https:\/\/www.este.com.py\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/esteadmpy","https:\/\/www.instagram.com\/esteadmpy\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.este.com.py\/pt\/wp-json\/wp\/v2\/pages\/13"}],"collection":[{"href":"https:\/\/www.este.com.py\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.este.com.py\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.este.com.py\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.este.com.py\/pt\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":7,"href":"https:\/\/www.este.com.py\/pt\/wp-json\/wp\/v2\/pages\/13\/revisions"}],"predecessor-version":[{"id":362,"href":"https:\/\/www.este.com.py\/pt\/wp-json\/wp\/v2\/pages\/13\/revisions\/362"}],"wp:attachment":[{"href":"https:\/\/www.este.com.py\/pt\/wp-json\/wp\/v2\/media?parent=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}